{"id":86204,"date":"2023-02-15T00:00:00","date_gmt":"2023-02-14T23:00:00","guid":{"rendered":"https:\/\/www.growbarato.net\/blog\/marihuana-negra\/"},"modified":"2026-08-05T09:11:46","modified_gmt":"2026-08-05T07:11:46","slug":"marihuana-negra","status":"publish","type":"post","link":"https:\/\/www.growbarato.net\/blog\/marihuana-negra\/","title":{"rendered":"Todo sobre la marihuana negra"},"content":{"rendered":"\n<p>Las plantas de cannabis pueden adquirir diferentes colores, existiendo as\u00ed diferentes tonalidades como la <a href=\"https:\/\/www.growbarato.net\/blog\/marihuana-roja-caracteristicas\/\">marihuana roja<\/a>,&nbsp; las <a href=\"https:\/\/www.growbarato.net\/824-semillas-de-marihuana-morada\">plantas de marihuana morada<\/a> o azul. Una de las menos conocidas es la llamada <strong>marihuana negra,<\/strong> que destaca por la <strong>tonalidad de sus hojas, d\u00e1ndole una presencia \u00fanica y diferente al resto de gen\u00e9ticas.<\/strong> Se trata de cepas raras y singulares capaces de ofrecer coloraciones m\u00e1s oscuras, si bien el negro solo aparece bajo ciertas condiciones medioambientales espec\u00edficas. Para entender c\u00f3mo sucede este proceso, se ha recopilado toda la informaci\u00f3n sobre las mismas.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<label for=\"ez-toc-cssicon-toggle-item-6a98ad8196df6\" class=\"ez-toc-cssicon-toggle-label\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a98ad8196df6\"  \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.growbarato.net\/blog\/marihuana-negra\/#%C2%BFComo_se_forma_la_marihuana_de_colores\" >\u00bfC\u00f3mo se forma la marihuana de colores?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.growbarato.net\/blog\/marihuana-negra\/#%C2%BFQue_es_la_marihuana_negra\" >\u00bfQu\u00e9 es la marihuana negra?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.growbarato.net\/blog\/marihuana-negra\/#%C2%BFEs_la_marihuana_negra_mas_potente\" >\u00bfEs la marihuana negra m\u00e1s potente?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.growbarato.net\/blog\/marihuana-negra\/#Las_mejores_variedades_de_marihuana_negra\" >Las mejores variedades de marihuana negra<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.growbarato.net\/blog\/marihuana-negra\/#Black_Domina\" >Black Domina<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.growbarato.net\/blog\/marihuana-negra\/#Black_Jack\" >Black Jack<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.growbarato.net\/blog\/marihuana-negra\/#Black_Domina-2\" >Black Domina<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_se_forma_la_marihuana_de_colores\"><\/span><strong>\u00bfC\u00f3mo se forma la marihuana de colores?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>El cannabis puede tomar <strong>diferentes tonalidades dependiendo de ciertos factores de cultivo. <\/strong>La causante de estas tonalidades \u00fanicas son las antocianinas, principalmente, un tipo de flavonoide, con efectos antioxidantes el cual es el responsable de la pigmentaci\u00f3n de muchas plantas.<\/p>\n\n\n\n<p>Actualmente, se han identificado m\u00e1s de <strong>500 antocianinas que son las responsables de proporcionar tonalidades rojas,<\/strong> moradas o azules a las plantas de marihuana. A medida que la planta madura, \u00e9sta aumenta la producci\u00f3n de estos flavonoides lo que explica porque los ejemplares <strong>j\u00f3venes suelen ser m\u00e1s verdes,<\/strong> mientras las maduras cambian a colores m\u00e1s oscuros.&nbsp;<\/p>\n\n\n\n<p>Estas tonalidades tambi\u00e9n dependen de <strong>ciertos factores como el pH o la temperatura.<\/strong> As\u00ed, las plantas de cannabis que se cultivan en climas m\u00e1s c\u00e1lidos y mediterr\u00e1neos tienden a tener un <strong>color verde m\u00e1s brillante y n\u00edtido.<\/strong> Por otra parte, aquellas germinadas en climas m\u00e1s fr\u00edos producen un color azulado con tonos morados, es decir m\u00e1s oscuras.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2023\/03\/marihuana-negra-que-es.jpg\" alt=\"Marihuana negra: \u00bfQu\u00e9 es?\" class=\"wp-image-57925\"\/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_la_marihuana_negra\"><\/span><strong>\u00bfQu\u00e9 es la marihuana negra?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La marihuana negra se caracteriza por <strong>tonos m\u00e1s oscuros, casi negros<\/strong>. Estos tonos surgen cuando hay muchas antocianinas presentes, las cuales est\u00e1n reaccionando a los cambios del entorno.<\/p>\n\n\n\n<p>Su funci\u00f3n principal es <strong>evitar la congelaci\u00f3n de la planta,<\/strong> por lo que cuando las temperaturas bajan intentar\u00e1n evitar que el agua de la planta del cannabis se congele. Por lo tanto, a climas m\u00e1s fr\u00edos o m\u00e1s oscuros ser\u00e1n los colores.&nbsp;<\/p>\n\n\n\n<p>Otro de los factores que <strong>pueden afectar al color de estas plantas es el pH del suelo. <\/strong>Normalmente la marihuana prefiere un sustrato ligeramente \u00e1cido. Si se acidifica el sustrato, las antocianinas har\u00e1n que la planta tenga un color rojo brillante. Por otro lado, si el <strong>pH es neutro, los tonos ser\u00e1n cada vez m\u00e1s oscuros<\/strong>. Para obtener unos buenos resultados este debe encontrarse entre 5,8 y 6,8.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFEs_la_marihuana_negra_mas_potente\"><\/span><strong>\u00bfEs la marihuana negra m\u00e1s potente?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Hoy en d\u00eda, existen en el mercado cepas Black que se caracterizan por <strong>descender de gen\u00e9ticas con un fenotipo recesivo<\/strong> que permite convertir la glucosa en antocianinas y las cuales heredan el gen recesivo de la planta madre.<\/p>\n\n\n\n<p>Cuando los cultivadores se encuentran con este tipo de plantas de marihuana les surgen dudas sobre las <strong>propiedades organol\u00e9pticas o los efectos que estas tendr\u00e1. <\/strong>Sin embargo, se debe tener en cuenta que el color de la marihuana negra \u00fanicamente influye \u00fanicamente en el aspecto. As\u00ed pues, el nivel de THC o sus aromas depender\u00e1 de las caracter\u00edsticas de cada cepa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Las_mejores_variedades_de_marihuana_negra\"><\/span><strong>Las mejores variedades de marihuana negra<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Entre algunas de las variedades Black que se pueden adquirir en la actualidad con estas caracter\u00edsticas destacan:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Black_Domina\"><\/span><strong>Black Domina<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><a href=\"https:\/\/www.growbarato.net\/semillas-a-granel-feminizadas\/2316-black-domina-100-feminizada.html\" data-type=\"link\" data-id=\"https:\/\/www.growbarato.net\/semillas-a-granel-feminizadas\/2316-black-domina-100-feminizada.html\">Black Domina<\/a> ofrece bonitos ejemplares \u00fanicos y homog\u00e9neos. Resalta por una hoja ancha, de color verde oscuro y cogollos compactos llenos de resina. Su <strong>sabor es dulce con toques incensados.<\/strong> Su efecto es puramente \u00edndico, proporcionando una relajaci\u00f3n profunda y potente.\u00a0 Su <strong>alto porcentaje de CBD <\/strong>hace que sea perfecto para aquellos que buscan una semilla medicinal y terap\u00e9utica.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2016\/12\/black-domina.jpg\" alt=\"Black Domina\" class=\"wp-image-57928\"\/><\/figure>\n<\/div>\n\n\n<p><strong>Caracter\u00edsticas de Black Domina<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sativa\/\u00cdndica:<\/strong> 5\/95%<\/li>\n\n\n\n<li><strong>Floraci\u00f3n: <\/strong>8\/9 semanas interior. Finales de septiembre outdoor.<\/li>\n\n\n\n<li><strong>Producci\u00f3n:<\/strong> 450-500 gramos por metro cuadrado indoor y hasta 1 kg por planta .<\/li>\n\n\n\n<li><strong>Altura: <\/strong>entre<strong> <\/strong>60 y 90 cm interior. 1,5-2,5 m en exterior.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Black_Jack\"><\/span><strong>Black Jack<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><a href=\"https:\/\/www.growbarato.net\/sweet-seeds\/310-black-jack-marihuana.html\">Black Jack<\/a> de Sweet Seeds posee un <strong>fuerte sabor a incienso,<\/strong> con un fondo dulce&nbsp; y alimonado, que recuerda al aroma de la m\u00edtica Jack Herer. Con ellas, se consiguen extracciones, gracias a las altas producciones de resina que genera. Las sensaciones que regala <strong>mezclan una fuerte sensaci\u00f3n euf\u00f3rica<\/strong> con una potente relajaci\u00f3n y un efecto sedante, por su perfecto equilibrio entre sativa e \u00edndica.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2023\/03\/black-jack-marihuana-negra.jpg\" alt=\"Black Jack: marihuana negra\" class=\"wp-image-57926\"\/><\/figure>\n<\/div>\n\n\n<p><strong>Caracter\u00edsticas de Black Jack:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sativa\/\u00cdndica:<\/strong> 50\/50%.<\/li>\n\n\n\n<li><strong>Floraci\u00f3n:<\/strong> 60-70 d\u00edas en interior. Mediados de octubre en exterior.<\/li>\n\n\n\n<li><strong>Producci\u00f3n:<\/strong> 500 gramos por metro cuadrado indoor y 700 gramos por planta en exterior.<\/li>\n\n\n\n<li><strong>Altura:<\/strong> hasta 1,8m en interior. 1,8- 2,5m en exterior.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Black_Domina-2\"><\/span><strong>Black Domina<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><a href=\"https:\/\/www.growbarato.net\/sensi-seeds\/3806-black-domina.html\">Black Domina<\/a>, una de <a href=\"https:\/\/www.growbarato.net\/76-sensi-seeds\">las gen\u00e9ticas cl\u00e1sicas de Sensi Seeds<\/a>, procedente del cruce entre tres de las variedades \u00edndicas <strong>m\u00e1s potentes del mundo como Northern Lights, Ortega, Hash Plan y Afghani S.A.<\/strong> \u00c9sta cuenta con una incre\u00edble capacidad para producir resina, lo que hace que se convierta en la <strong>semilla perfecta para los amantes de las extracciones.<\/strong> Destaca por una gran potencia y una predominancia \u00edndica que le permite regalar sensaciones relajantes, calmando los dolores musculares.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2023\/03\/black-domina-sensi-seeds.jpg\" alt=\"Black Domina de Sensi Seeds\" class=\"wp-image-57927\"\/><\/figure>\n<\/div>\n\n\n<p><strong>Caracter\u00edsticas de Black Domina de Sensi Seeds:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sativa\/Indica: <\/strong>5\/95%<\/li>\n\n\n\n<li><strong>Floraci\u00f3n: <\/strong>8 semanas interior, finales de Septiembre en exterior.<\/li>\n\n\n\n<li><strong>Producci\u00f3n: <\/strong>hasta 500 gramos por metro cuadrado indoor y 750 gramos por planta outdoor.<\/li>\n\n\n\n<li><strong>Altura: <\/strong>60-90cm interior.&nbsp; Entre 1,5 y 2,5 m en exterior.<\/li>\n<\/ul>\n\n\n\n<p>La <strong>marihuana negra<\/strong> es una de las menos conocidas pero m\u00e1s especiales por su aspecto caracter\u00edstico y m\u00e1s oscuro, que le dan un toque diferente a los cultivos de cannabis.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Las plantas de cannabis pueden adquirir diferentes colores, existiendo as\u00ed diferentes tonalidades como la marihuana roja,&nbsp; las plantas de marihuana morada o azul. Una de las menos conocidas es la llamada marihuana negra, que destaca por la tonalidad de sus hojas, d\u00e1ndole una presencia \u00fanica y diferente al resto de gen\u00e9ticas. Se trata de cepas\u2026 <span class=\"leermas\" onclick=\"window.location.href='https:\/\/www.growbarato.net\/blog\/marihuana-negra\/'\">Seguir leyendo<\/span ><\/p>\n","protected":false},"author":18,"featured_media":96885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-86204","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cultivos-de-marihuana"},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":1,"sum_votes":5},"_links":{"self":[{"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/posts\/86204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/comments?post=86204"}],"version-history":[{"count":8,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/posts\/86204\/revisions"}],"predecessor-version":[{"id":240332,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/posts\/86204\/revisions\/240332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/media\/96885"}],"wp:attachment":[{"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/media?parent=86204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/categories?post=86204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/tags?post=86204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}