{"id":86056,"date":"2022-04-13T00:00:00","date_gmt":"2022-04-12T22:00:00","guid":{"rendered":"https:\/\/www.growbarato.net\/blog\/micropropagacion-cannabis\/"},"modified":"2026-06-26T12:57:52","modified_gmt":"2026-06-26T10:57:52","slug":"micropropagacion-cannabis","status":"publish","type":"post","link":"https:\/\/www.growbarato.net\/blog\/micropropagacion-cannabis\/","title":{"rendered":"La micropropagaci\u00f3n en el cultivo de cannabis"},"content":{"rendered":"\n<p>La <strong>evoluci\u00f3n en el mundo de los cultivos<\/strong> ha dado grandes saltos en los \u00faltimos dos siglos. Un incre\u00edble avance, que ha pasado del barbecho en los cultivos para descansar la tierra, hasta los nuevos m\u00e9todos de <strong>reproducci\u00f3n celular de las plantas<\/strong>. La actual tendencia a legalizar o despenalizar la marihuana ha abierto las puertas a nuevas modalidades de cultivo. Desarrollo e implementaci\u00f3n de la hidropon\u00eda, cultivos con <a href=\"https:\/\/www.growbarato.net\/blog\/semillas-medicinales-marihuana-alto-contenido-cbd\/\">variedades ricas en CBD<\/a> o nuevas formas de producir plantas como la <strong><em>micropropagaci\u00f3n de Cannabis<\/em><\/strong>.<\/p>\n\n\n\n<p>Cada cultivador busca <strong>las mejores condiciones<\/strong> para sus plantas, especialmente con la higiene y la salud. Los avances cient\u00edficos en el campo de la bot\u00e1nica ofrecen alternativas a los m\u00e9todos de cultivo y reproducci\u00f3n de ejemplares que se han utilizado siempre. Uno de estos es la micropropagaci\u00f3n, o <strong>reproducci\u00f3n por cultivo de tejidos<\/strong>, como el <a href=\"https:\/\/www.growbarato.net\/blog\/tissue-culture-que-es\/\">tissue culture<\/a>. Una t\u00e9cnica novedosa, diferente a la clonaci\u00f3n mediante esquejes, que consigue ejemplares sanos, sin infecciones y perfectamente capacitados para el cultivo.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<label for=\"ez-toc-cssicon-toggle-item-6a9877104df24\" class=\"ez-toc-cssicon-toggle-label\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a9877104df24\"  \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.growbarato.net\/blog\/micropropagacion-cannabis\/#%C2%BFQue_es_la_micropropagacion_de_cannabis\" >\u00bfQu\u00e9 es la micropropagaci\u00f3n de cannabis?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.growbarato.net\/blog\/micropropagacion-cannabis\/#La_biotecnologia_vegetal_y_su_evolucion_hasta_la_actualidad\" >La biotecnolog\u00eda vegetal y su evoluci\u00f3n hasta la actualidad<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.growbarato.net\/blog\/micropropagacion-cannabis\/#%C2%BFComo_es_el_proceso_de_micropropagacion\" >\u00bfC\u00f3mo es el proceso de micropropagaci\u00f3n?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.growbarato.net\/blog\/micropropagacion-cannabis\/#Los_tipos_de_micropropagacion_de_cannabis_mas_conocidos\" >Los tipos de micropropagaci\u00f3n de cannabis m\u00e1s conocidos<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.growbarato.net\/blog\/micropropagacion-cannabis\/#%C2%BFHasta_donde_puede_llegar_la_micropropagacion_de_cannabis\" >\u00bfHasta d\u00f3nde puede llegar la micropropagaci\u00f3n de cannabis?<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_la_micropropagacion_de_cannabis\"><\/span><strong>\u00bfQu\u00e9 es la micropropagaci\u00f3n de cannabis?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>T\u00e9cnicamente, la micropropagaci\u00f3n consiste en el <strong>cultivo <em>in vitro<\/em> de plantas<\/strong>, a trav\u00e9s de c\u00e9lulas o tejidos vegetales de una madre seleccionada. Este tejido, conocido como <strong>\u2018explante\u2019<\/strong>, se introduce en un recipiente esterilizado con un l\u00edquido neutro para que se desarrolle. Gracias a la micropropagaci\u00f3n es posible <strong>crear miles de clones id\u00e9nticos<\/strong> de la misma planta,<strong> sin enfermedades<\/strong> y con las propiedades organol\u00e9pticas intactas.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"453\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2021\/09\/micropropagacion-de-cannabis.jpg\" alt=\"micropropagacion de cannabis\" class=\"wp-image-53176\" title=\"Micropropagaci\u00f3n de cannabis\" srcset=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2021\/09\/micropropagacion-de-cannabis.jpg 600w, https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2021\/09\/micropropagacion-de-cannabis-300x227.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n<p>Dentro del panorama cann\u00e1bico, este proceso de reproducci\u00f3n supone un <strong>gran avance<\/strong> y puede ayudar a los cultivadores y empresas. Al replicar las propiedades de la planta, se convierte en un <strong>clon exacto<\/strong>: misma altura, mismas necesidades nutritivas, mismos efectos, mismos matices y una composici\u00f3n de cannabinoides igual. Esto facilita las labores de cultivo, y ser\u00eda posible <strong>controlar la producci\u00f3n<\/strong> r\u00e1pidamente y no exceder los valores permitidos de THC por ley. Una posible puerta para la <strong>investigaci\u00f3n<\/strong>, cuyos resultados pueden marcar un antes y un despu\u00e9s en el panorama cann\u00e1bico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"La_biotecnologia_vegetal_y_su_evolucion_hasta_la_actualidad\"><\/span><strong>La biotecnolog\u00eda vegetal y su evoluci\u00f3n hasta la actualidad<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>La creaci\u00f3n de ejemplares funcionales a trav\u00e9s de micropropagaci\u00f3n es ahora una t\u00e9cnica generalizada y utilizada en bot\u00e1nica. No obstante, sus inicios se encuentran a <strong>principios del siglo XX<\/strong>. El bot\u00e1nico austr\u00edaco <strong>Gottlieb Haberlandt (1854-1945)<\/strong> utiliz\u00f3 la idea de la <strong>totipotencia <\/strong>celular, por la cual las c\u00e9lulas vegetales se pueden regenerar en plantas completas.&nbsp;<\/p>\n\n\n\n<p>Siguiendo este modelo, consigui\u00f3 estandarizar un cultivo de tejidos vegetales. Es conocido como el padre de esta t\u00e9cnica, y gracias a su investigaci\u00f3n, en los a\u00f1os 30 se empezaron a aplicar las <strong>hormonas vegetales<\/strong> en el proceso.<\/p>\n\n\n\n<p>Gracias a la introducci\u00f3n de hormonas como la <strong>citocinina<\/strong>, encargada de propiciar la divisi\u00f3n celular y la organog\u00e9nesis, se avanz\u00f3 en gran medida. En los a\u00f1os 60, se pudieron aislar los primeros <strong>cultivos libres de virus<\/strong> (meristemos apicales). Y a ra\u00edz de estos acontecimientos, se generaliz\u00f3 la micropropagaci\u00f3n para diversos procesos: evitar la desaparici\u00f3n de especies vegetales, cultivos en masa, proliferaci\u00f3n de especies en ciertos h\u00e1bitats. El t\u00e9rmino micropropagaci\u00f3n surge en <strong>1986<\/strong>, y desde entonces forma parte de la biotecnolog\u00eda vegetal, en muchas investigaciones y empresas.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"453\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2021\/09\/plantas-micropropagacion.jpg\" alt=\"biotecnologia vegetal\" class=\"wp-image-53177\" title=\"Biotecnolog\u00eda vegetal\" srcset=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2021\/09\/plantas-micropropagacion.jpg 600w, https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2021\/09\/plantas-micropropagacion-300x227.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_es_el_proceso_de_micropropagacion\"><\/span><strong>\u00bfC\u00f3mo es el proceso de micropropagaci\u00f3n?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Dentro del proceso de reproducci\u00f3n a partir de c\u00e9lulas o tejidos vegetales, se encuentran <strong>diferentes etapas<\/strong>. Sin embargo, en funci\u00f3n del cultivo que se haga, se pueden recortar los procesos y simplificarlos, o alargar y a\u00f1adir m\u00e1s fases. Por ejemplo, las especies forestales requieren de un tiempo extra, conocido como \u201cendurecimiento\u201d.\u00a0<\/p>\n\n\n\n<p>En un primer momento, los cultivos deben realizarse <em>in vitro<\/em>, para preservar una <strong>atm\u00f3sfera esterilizada<\/strong> y evitar infecciones parasitarias, hongos y enfermedades. En esta parte del proceso, influye en gran medida la <strong>elecci\u00f3n de la madre<\/strong>. Un ejemplar sano y fuerte es la mejor opci\u00f3n, ya que los <a href=\"https:\/\/www.growbarato.net\/boom-nutrients\/5117-cloner-boom.html\"><strong>clones<\/strong><\/a> tendr\u00e1n las mismas propiedades. Despu\u00e9s de la selecci\u00f3n, se debe esterilizar la <strong>materia vegetal<\/strong> seleccionada, para as\u00ed evitar la proliferaci\u00f3n de pat\u00f3genos dentro del recipiente.<\/p>\n\n\n\n\n\n\n<p>Posteriormente, se debe a\u00f1adir el <strong>tejido o las c\u00e9lulas<\/strong> al recipiente con un l\u00edquido est\u00e9ril, para que se <strong>desarrolle la ra\u00edz y comience a brotar<\/strong>. Este proceso debe realizarse siempre dentro de una <strong>cabina de flujo laminar<\/strong>, para que el ambiente est\u00e9 perfectamente depurado.&nbsp;<\/p>\n\n\n\n<p>Dentro de la probeta se busca la <strong>m\u00e1xima reproducci\u00f3n de explantes<\/strong>, para producir el mayor n\u00famero de clones. Para ello, utilizan <strong>hormonas <\/strong>reguladoras del crecimiento, que fomentan el crecimiento de la ra\u00edz. Durante esta parte del proceso, <strong>es posible cultivar <em>ex vitro<\/em><\/strong>, ya que el proceso de <strong>aclimataci\u00f3n <\/strong>a la tierra se debe producir en alg\u00fan momento. Influir\u00e1 la iluminaci\u00f3n, la adaptabilidad de la planta y el m\u00e9todo empleado.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"453\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2021\/09\/clones-cannabis.jpg\" alt=\"clones cannabis\" class=\"wp-image-53178\" title=\"Clones de cannabis\" srcset=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2021\/09\/clones-cannabis.jpg 600w, https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2021\/09\/clones-cannabis-300x227.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Los_tipos_de_micropropagacion_de_cannabis_mas_conocidos\"><\/span><strong>Los tipos de micropropagaci\u00f3n de cannabis m\u00e1s conocidos<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Organog\u00e9nesis<\/strong>: Utiliza <strong>yemas vegetativas <\/strong>de la planta para obtener tallos, ra\u00edces o flores. Es el m\u00e1s utilizado, y ofrece resultados r\u00e1pidos y de calidad. La organog\u00e9nesis puede realizarse de forma <strong>directa o indirecta<\/strong>. En ambas, se busca la <strong>respuesta morfogen\u00e9tica<\/strong> para formar los \u00f3rganos, y de ah\u00ed generar la planta completa.<\/li>\n\n\n\n<li><strong>Embriog\u00e9nesis<\/strong>: Mediante una <strong>secci\u00f3n de tejido som\u00e1tico<\/strong>, se busca la formaci\u00f3n de embriones som\u00e1ticos. Estos embriones germinan y forman un tallo y la rad\u00edcula de forma simult\u00e1nea. De la misma forma que el anterior m\u00e9todo, se produce de dos maneras:\n<ul class=\"wp-block-list\">\n<li><strong>Embriog\u00e9nesis directa<\/strong>: Se produce cuando los embriones <strong>producen directamente los tejidos<\/strong> sobre los que se desarrollar\u00e1 la planta.<\/li>\n\n\n\n<li><strong>Embriog\u00e9nesis indirecta<\/strong>: Requiere una <strong>inducci\u00f3n para desordenar las c\u00e9lulas y formar un callo<\/strong>. A partir de ese cultivo, se produce un tallo adventicio o semillas som\u00e1ticas para cultivo.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFHasta_donde_puede_llegar_la_micropropagacion_de_cannabis\"><\/span><strong>\u00bfHasta d\u00f3nde puede llegar la micropropagaci\u00f3n de cannabis?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Actualmente, este tipo de cultivos <strong>debe realizarse en un laboratorio<\/strong>. Requieren mucho material t\u00e9cnico y un ambiente est\u00e9ril para evitar las infecciones. Esto supone un <strong>desembolso econ\u00f3mico<\/strong> inviable para muchos productores y empresarios. Sin embargo, se busca <strong>estandarizar el proceso<\/strong> y abaratar los materiales, para que las empresas puedan implantar estos procesos.\u00a0<\/p>\n\n\n\n<p>De esta forma, los precios se regulan, para que cultivadores y empresas tengan un mayor margen y pongan en pr\u00e1ctica este tipo de procesos. Requiere <strong>t\u00e9cnica y conocimiento<\/strong>, pero es un paso importante en la regulaci\u00f3n del cultivo y uso del cannabis.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>La evoluci\u00f3n en el mundo de los cultivos ha dado grandes saltos en los \u00faltimos dos siglos. Un incre\u00edble avance, que ha pasado del barbecho en los cultivos para descansar la tierra, hasta los nuevos m\u00e9todos de reproducci\u00f3n celular de las plantas. La actual tendencia a legalizar o despenalizar la marihuana ha abierto las puertas\u2026 <span class=\"leermas\" onclick=\"window.location.href='https:\/\/www.growbarato.net\/blog\/micropropagacion-cannabis\/'\">Seguir leyendo<\/span ><\/p>\n","protected":false},"author":18,"featured_media":53176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-86056","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cultivos-de-marihuana"},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":2,"sum_votes":8},"_links":{"self":[{"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/posts\/86056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/comments?post=86056"}],"version-history":[{"count":9,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/posts\/86056\/revisions"}],"predecessor-version":[{"id":236570,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/posts\/86056\/revisions\/236570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/media\/53176"}],"wp:attachment":[{"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/media?parent=86056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/categories?post=86056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.growbarato.net\/blog\/wp-json\/wp\/v2\/tags?post=86056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}